{"id":4751,"date":"2023-02-09T22:28:30","date_gmt":"2023-02-09T22:28:30","guid":{"rendered":"https:\/\/tvnativoos.com.br\/wfe\/?p=4751"},"modified":"2023-02-09T22:29:16","modified_gmt":"2023-02-09T22:29:16","slug":"compra-de-maquinas-e-maior-entre-os-agricultores-familiares","status":"publish","type":"post","link":"https:\/\/tvnativoos.com.br\/wfe\/compra-de-maquinas-e-maior-entre-os-agricultores-familiares\/","title":{"rendered":"Compra de m\u00e1quinas \u00e9 maior entre os agricultores familiares"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A percep\u00e7\u00e3o do produtor rural de que \u00e9 preciso trabalhar, independentemente do governo eleito para comandar o pa\u00eds na \u00faltima elei\u00e7\u00e3o, \u00e9 quase un\u00e2nime na 35\u00aa edi\u00e7\u00e3o do Show Rural Coopavel. A realiza\u00e7\u00e3o de neg\u00f3cios, no entanto, difere de um perfil produtivo para outro. Enquanto as multinacionais e as grandes fabricantes de\u00a0m\u00e1quinas e implementos agr\u00edcolas\u00a0visam neg\u00f3cios em m\u00e9dio e longo prazo, as de menor porte, onde as vendas oscilam entre R$ 30 e R$ 100 mil, comemoram a procura de implementos com entrega imediata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPercebemos um otimismo dos produtores e concession\u00e1rios, nitidamente, o \u00e2nimo em fazer neg\u00f3cios, seja por parte do produtor, aproveitando as condi\u00e7\u00f5es especiais da feira, como dos concession\u00e1rios, que fecham pacotes, j\u00e1 com proje\u00e7\u00e3o aos pr\u00f3ximos meses, com cen\u00e1rio de preparo de solo\u201d, assegura o coordenador de Marketing da S\u00e3o Jos\u00e9 Industrial, Daniel Ribeiro. As vendas s\u00e3o realizadas principalmente para agricultores familiares do Paran\u00e1, que praticamente n\u00e3o tiveram perdas com estiagem neste ano e est\u00e3o capitalizados.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por necessidade imediata, a procura por equipamento para a colheita da safra 2022\/2023 desponta, diz Ribeiro, principalmente porque o p\u00fablico da empresa nao depende de\u00a0financiamento banc\u00e1rio. \u201cO perfil de investimento em nossos equipamentos vai at\u00e9 R$ 150 mil. Ou a revenda ou a cooperativa financia o produtor\u201d, revela. Na sequ\u00eancia, est\u00e3o os equipamentos para prepara\u00e7\u00e3o de solo no Paran\u00e1, em S\u00e3o Paulo, em Mato Grosso do Sul e em Santa Catarina, para avicultura, suinocultura, produ\u00e7\u00e3o de leite, piscicultura, atividades realizadas em \u00e1reas entre 50 hectares e 100 hectares. \u201cNo Rio Grande do Sul, a expectativa de venda volta-se para a Expodireto Cotrijal\u201d, avalia.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A avicultura tamb\u00e9m \u00e9 o foco da\u00a0LS Tractor\u00a0neste Show Rural. A fabricante trouxe como carro-chefe um modelo voltado para uso \u201cin door\u201d, em ambientes fechados, que serve para o manejo da cama de frango, por exemplo. \u201c\u00c9 a m\u00e1quina dentro do galp\u00e3o, dentro de uma estufa\u201d, detalha o gerente de Marketing da LS Tractor, Astor Kilpp. A estrat\u00e9gia, no entanto, tamb\u00e9m acolhe outros perfis produtivos, mas estimula o relacionamento com clientes que utilizam financiamento federal. \u201cFizemos um local muito confort\u00e1vel, cuidando de detalhes para que os clientes se sintam bem, buscando a aproxima\u00e7\u00e3o da realidade do produtor\u201d, destaca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No estande, localizado logo na entrada do\u00a0Parque Tecnol\u00f3gico Coopavel,\u00a0em Cascavel, \u00e9 comum ver pais acompanhados dos filhos na busca por tecnologia. \u201cO jovem quer acabar com o desperd\u00edcio na propriedade. \u00c9 a grande revolu\u00e7\u00e3o que vai acontecer com a tecnologia no campo, de cinco a dez anos, como foi quando chegou o plantio direto e desafiou o produtor a plantar sem virar o solo\u201d, compara. Valmir Schlickmann, produtor de soja, milho e trigo em Tr\u00eas Barras do Paran\u00e1, munic\u00edpio do Oeste paranaense, e cliente da LS Tractor, \u00e9 um dos que esteve no Show Rural Digital apenas para \u201colhar\u201d. Esperando o in\u00edcio da colheita de ver\u00e3o e sem perspectiva de financiamento oficial, preferiu n\u00e3o arriscar um novo investimento. Mas marcou presen\u00e7a no estande da fabricante e estreitou relacionamentos. \u201cN\u00e3o queremos arriscar tanto. Estamos aguardando um pouco para ver qual ser\u00e1 a realidade da produ\u00e7\u00e3o deste ano, j\u00e1 que os juros de banco n\u00e3o s\u00e3o compat\u00edveis com nossa realidade\u201d, desabafa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com um filho universit\u00e1rio estudando agronomia na Universidade Federal de Santa Maria (UFSM), o produtor planta 220 hectares que, juntamente com \u00e1reas arrendadas, chegam a 310 hectares. A totalidade da \u00e1rea \u00e9 semeada com soja, o carro-chefe da propriedade. Na sequ\u00eancia, Schlickmann planta a safrinha de milho e a de trigo. \u201cMas, este ano, vamos ampliar a \u00e1rea de trigo por causa da rentabilidade\u201d, adianta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A gest\u00e3o da propriedade ainda \u00e9 feita no papel, mas o produtor conta com\u00a0plantadeira, colheitadeira e pulverizador. E assegura que a tecnologia n\u00e3o est\u00e1 somente no maquin\u00e1rio, mas no conhecimento aplicado \u00e0 qualidade do solo, do manejo e das cultivares escolhidas. \u201cN\u00e3o \u00e9 ser um simples agricultor. N\u00e3o pode ir atr\u00e1s de v\u00e1rias outras opini\u00f5es porque cada um tem a sua, assim como cada um tem a sua realidade\u201d, argumenta. Schlickmann, que aproveita a exposi\u00e7\u00e3o para conhecer as novidades em tecnologia, defende que as inova\u00e7\u00f5es sejam aplicadas de acordo com a necessidade de cada produtor ao longo do tempo. \u201cA feira deixa um conhecimento para que, futuramente, a gente possa aplicar na pr\u00f3pria agricultura\u201d, diz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte Correio do Povo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se inscreva em nosso canal do&nbsp;<strong><a href=\"https:\/\/www.youtube.com\/@tvnativoos\">youtube.com\/@tvnativoos<\/a><\/strong>, curta nossa p\u00e1gina no&nbsp;<strong><a href=\"https:\/\/www.facebook.com\/tvnativoos\">facebook<\/a><\/strong>,&nbsp;<strong><a href=\"https:\/\/www.instagram.com\/tvnativoos\/\">instagram<\/a><\/strong>&nbsp;e veja nossa programa\u00e7\u00e3o ao vivo pelo canal 6 da Claro Net ou pelo portal&nbsp;<strong><a href=\"http:\/\/tvnativoos.com.br\/wfe\/\">tvnativoos.com.br.<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No m\u00eas de mar\u00e7o a&nbsp;<strong><a href=\"http:\/\/tvnativoos.com.br\/wfe\/\">TV Nativoos<\/a><\/strong>&nbsp;est\u00e1 programando muitas novidades na \u00e1rea de comunica\u00e7\u00e3o!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A percep\u00e7\u00e3o do produtor rural de que \u00e9 preciso trabalhar, independentemente do governo eleito para comandar o pa\u00eds na \u00faltima [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4752,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[858,862,65],"class_list":["post-4751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-agronegocio-2","tag-rural","tag-tvnativoos"],"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts\/4751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/comments?post=4751"}],"version-history":[{"count":2,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts\/4751\/revisions"}],"predecessor-version":[{"id":4754,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts\/4751\/revisions\/4754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/media\/4752"}],"wp:attachment":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/media?parent=4751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/categories?post=4751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/tags?post=4751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}