{"id":3863,"date":"2023-01-12T02:54:01","date_gmt":"2023-01-12T02:54:01","guid":{"rendered":"https:\/\/tvnativoos.com.br\/wfe\/?p=3863"},"modified":"2023-01-12T02:54:02","modified_gmt":"2023-01-12T02:54:02","slug":"demonstracao-de-forca-do-estado-esvazia-manifestacao-golpista","status":"publish","type":"post","link":"https:\/\/tvnativoos.com.br\/wfe\/demonstracao-de-forca-do-estado-esvazia-manifestacao-golpista\/","title":{"rendered":"Demonstra\u00e7\u00e3o de for\u00e7a do Estado esvazia manifesta\u00e7\u00e3o golpista\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Em Porto Alegre, menos de uma dezena de pessoas atendeu \u00e0 convoca\u00e7\u00e3o para um ato no Parc\u00e3o.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Policiais militares, federais e civis, tropas de elite de diferentes for\u00e7as, militares do Ex\u00e9rcito, bombeiros e viaturas de todos os tipos (carros, motos, camionetas, micro\u00f4nibus, \u00f4nibus, ambul\u00e2ncias e at\u00e9 helic\u00f3pteros)\u00a0ocuparam a Esplanada dos Minist\u00e9rios\u00a0e intimidaram radicais, em Brasilia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O\u00a0ato convocado por golpistas, em Bras\u00edlia, foi esvaziado. \u00c0s 19h3omin, n\u00e3o havia sequer um &#8220;patriota&#8221; de verde e amarelo pr\u00f3ximo \u00e0 Esplanada dos Minist\u00e9rios. Mais cedo, o interventor na Seguran\u00e7a Publica do Distrito Federal, Ricardo Cappelli, em entrevista coletiva, havia garantido:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em S\u00e3o Paulo, na avenida Paulista, o policiamento foi refor\u00e7ado. Grupos de 30 a 40 agentes da Pol\u00edcia Militar, alguns a cavalo, circulavam nas ruas do entorno do Masp. Policiais se posicionaram em duplas pr\u00f3ximo ao pr\u00e9dio da Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de S\u00e3o Paulo (Fiesp). O tr\u00e2nsito flu\u00eda sem obstru\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Moraes proibiu o bloqueio de vias em todo o pa\u00eds atendendo a um pedido da Advocacia-Geral da Uni\u00e3o (AGU), que acionou o Supremo ap\u00f3s o\u00a0governo Lula\u00a0detectar novas amea\u00e7as de golpe em mensagens que anunciavam uma &#8220;Mega Manifesta\u00e7\u00e3o Nacional pela Retomada do Poder&#8221; para esta quarta-feira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na Paulista, poucas pessoas vestidas de verde e amarelo e com a bandeira do Brasil chegaram a se posicionar em alguns pontos da avenida, mas nenhuma delas em grupo organizado. A maioria passava sem parar em frente ao Masp.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O estudante Bruno Fonseca, de 17 anos, chegou \u00e0 Paulista por volta das 19h em busca de &#8220;uma manifesta\u00e7\u00e3o pac\u00edfica e a favor da liberdade&#8221;. Ele, que diz ser de direita, afirmou tamb\u00e9m ser contr\u00e1rio aos atos de vandalismo registrados em Bras\u00edlia. &#8220;Vim para a manifesta\u00e7\u00e3o de segunda-feira, que era de maioria da esquerda, porque sou contra aquilo&#8221;, disse. Ele contou ter lido sobre a manifesta\u00e7\u00e3o desta quarta nas redes sociais, mas acredita que a decis\u00e3o de Moraes tenha motivado a baixa ades\u00e3o ao evento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nas redes sociais, usu\u00e1rios tamb\u00e9m disseram que a manifesta\u00e7\u00e3o seria, na verdade, falsa, e que o encontro n\u00e3o havia sido programado por defensores de Bolsonaro. Um dos jovens presentes na Paulista mostrou um tu\u00edte que atribu\u00eda a manifesta\u00e7\u00e3o a uma armadilha para criar pretexto para afastar o governador de S\u00e3o Paulo, Tarc\u00edsio de Freitas (Republicanos).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A possibilidade de uma manifesta\u00e7\u00e3o acontecer no local fez com que empresas da regi\u00e3o liberassem os funcion\u00e1rios do trabalho presencial. A Subse\u00e7\u00e3o Judici\u00e1ria de S\u00e3o Paulo tamb\u00e9m suspendeu atividades presenciais por causa da poss\u00edvel concentra\u00e7\u00e3o de manifestantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No Rio, tamb\u00e9m fracassou o ato de teor golpista convocado em grupos do WhatsApp, do Telegram e por perfis bolsonaristas nas redes sociais para ocorrer em Copacabana, na zona sul do Rio, na noite desta quarta. A manifesta\u00e7\u00e3o contra o governo Lula n\u00e3o reuniu nenhum apoiador na orla da praia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em grupos bolsonaristas, parte dos integrantes acusaram militantes de esquerda de promover a convoca\u00e7\u00e3o de um suposto &#8220;ato fake&#8221;. O objetivo seria infiltrar opositores para culpar os direitistas caso houvesse depreda\u00e7\u00e3o de patrim\u00f4nio. Acusar &#8211; sem nenhum prova &#8211; supostos esquerdistas infiltrados de vandalismo tem sido uma das estrat\u00e9gias da direita. O objetivo \u00e9 fugir da m\u00e1 repercuss\u00e3o do ataque ao Pal\u00e1cio do Planalto, ao Congresso Nacional e ao Supremo Tribunal Federal no domingo, 8. Na invas\u00e3o, os bolsonaristas quebraram vidros, jogaram cadeiras pelas janelas, destru\u00edram obras de arte valiosas e objetos hist\u00f3ricos preciosos, fizeram picha\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Prefeitura do Rio e o governo fluminense refor\u00e7aram a seguran\u00e7a no trecho do Posto 5 da Praia de Copacabana. Aquele era o local previsto para receber a manifesta\u00e7\u00e3o. Agentes da Guarda Municipal e policiais militares foram deslocados para aquele ponto da orla. Mas nenhum manifestante apareceu. A chuva tamb\u00e9m desestimulou o comparecimento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em Belo Horizonte, 1.400 c\u00e2meras monitoraram os atos, de acordo com Pol\u00edcia Militar. Na capital mineira, a ades\u00e3o foi baixa. Ademir Aparecido Pinheiro, 47 anos, auxiliar de servi\u00e7os gerais, morador do bairro S\u00e3o Gabriel, regi\u00e3o nordeste de Belo Horizonte, que se posiciona como conservador e eleitor de Bolsonaro, lamentou a aus\u00eancia de pessoas na manifesta\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte Correio do Povo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em Porto Alegre, menos de uma dezena de pessoas atendeu \u00e0 convoca\u00e7\u00e3o para um ato no Parc\u00e3o.\u00a0 Policiais militares, federais [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3864,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[794,691,792,793,65],"class_list":["post-3863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-distritofederal","tag-golpe","tag-golpistas","tag-terroristas","tag-tvnativoos"],"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts\/3863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/comments?post=3863"}],"version-history":[{"count":1,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts\/3863\/revisions"}],"predecessor-version":[{"id":3865,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts\/3863\/revisions\/3865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/media\/3864"}],"wp:attachment":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/media?parent=3863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/categories?post=3863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/tags?post=3863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}