{"id":32026,"date":"2026-03-23T13:43:42","date_gmt":"2026-03-23T13:43:42","guid":{"rendered":"https:\/\/tvnativoos.com.br\/wfe\/?p=32026"},"modified":"2026-03-23T13:43:44","modified_gmt":"2026-03-23T13:43:44","slug":"nativoos-esportes-inter-vitoria-no-beira-rio","status":"publish","type":"post","link":"https:\/\/tvnativoos.com.br\/wfe\/nativoos-esportes-inter-vitoria-no-beira-rio\/","title":{"rendered":"Nativoos Esportes &#8211; Inter, vit\u00f3ria no Beira-Rio"},"content":{"rendered":"\n<p>Zagueiro comemora fim da sequ\u00eancia sem vit\u00f3rias e exalta atua\u00e7\u00e3o coletiva no 2 a 0 sobre a Chapecoense<\/p>\n\n\n\n<p>A\u00a0<strong>vit\u00f3ria por 2 a 0 sobre a Chapecoense, neste domingo, no Beira-Rio<\/strong>, marcou n\u00e3o apenas a sa\u00edda do\u00a0<strong>Inter\u00a0<\/strong>da zona de rebaixamento, mas tamb\u00e9m um momento de al\u00edvio para o grupo colorado. Um dos l\u00edderes da equipe, o zagueiro Gabriel Mercado destacou a rea\u00e7\u00e3o constru\u00edda a partir da confian\u00e7a no trabalho da comiss\u00e3o t\u00e9cnica e do comprometimento dos jogadores. Segundo o defensor, o inc\u00f4modo com a situa\u00e7\u00e3o na tabela era evidente dentro do vesti\u00e1rio, mas nunca houve perda de confian\u00e7a no processo.<\/p>\n\n\n<div class=\"g g-7\"><div class=\"g-dyn a-62 c-1\"><a class=\"gofollow\" data-track=\"NjIsNyw2MA==\" href=\": http:\/\/teliga.corsan.com.br\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-17.23.17.jpeg\" \/><\/a><\/div><div class=\"g-dyn a-4 c-2\"><a class=\"gofollow\" data-track=\"NCw3LDYw\" href=\"https:\/\/arquitetalaurabaltar.com.br\/wfe\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2025\/01\/01-1.png\" \/><\/a><\/div><div class=\"g-dyn a-8 c-3\"><a class=\"gofollow\" data-track=\"OCw3LDYw\" href=\"https:\/\/www.facebook.com\/sonia.conti.7545\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2023\/06\/BANNERS-350X250-SONIA-CONTI-1-300x214-1.jpg\" \/><\/a><\/div><div class=\"g-dyn a-39 c-4\"><a class=\"gofollow\" data-track=\"MzksNyw2MA==\" href=\"https:\/\/tvnativoos.com.br\/wfe\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-17-at-19.58.28.jpeg\" \/><\/a><\/div><div class=\"g-dyn a-58 c-5\"><a class=\"gofollow\" data-track=\"NTgsNyw2MA==\" href=\"https:\/\/transformar.tramandai.rs.gov.br\/\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2026\/03\/TV-Nativoos-300-x-250-px.png\" \/><\/a><\/div><div class=\"g-dyn a-6 c-6\"><a class=\"gofollow\" data-track=\"Niw3LDYw\" href=\"#\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2023\/01\/banner-agua-kangen-e1701887476486.jpeg\" \/><\/a><\/div><div class=\"g-dyn a-7 c-7\"><a class=\"gofollow\" data-track=\"Nyw3LDYw\" href=\"https:\/\/inovaimoveis.rs\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2023\/06\/Banner-Inova-300x214-1.jpeg\" \/><\/a><\/div><\/div>\n\n\n<p>\u201cA gente estava incomodado com esse momento. Sabemos da exig\u00eancia que \u00e9 defender este clube, mas sempre acreditamos na comiss\u00e3o t\u00e9cnica e no que vinha sendo passado. O professor fez algumas mudan\u00e7as, o time respondeu bem e conseguimos vencer. Agora, vamos focar nos pr\u00f3ximos jogos para seguir subindo na tabela\u201d, afirmou.<\/p>\n\n\n\n<p>Al\u00e9m do resultado, Mercado valorizou o desempenho defensivo, j\u00e1 que o Inter voltou a n\u00e3o sofrer gols, algo que, segundo ele, vinha sendo motivo de cobran\u00e7a interna. \u201c\u00c9 uma alegria grande sair de campo sem ser vazado. Eu me cobrava muito por isso. Sabemos que todos participam, tanto na defesa quanto no ataque. Faltava transformar as chances em gols, e hoje conseguimos fazer dois e manter o zero atr\u00e1s\u201d, destacou.<\/p>\n\n\n<div class=\"g g-6\"><div class=\"g-dyn a-4 c-1\"><a class=\"gofollow\" data-track=\"NCw2LDYw\" href=\"https:\/\/arquitetalaurabaltar.com.br\/wfe\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2025\/01\/01-1.png\" \/><\/a><\/div><div class=\"g-dyn a-62 c-2\"><a class=\"gofollow\" data-track=\"NjIsNiw2MA==\" href=\": http:\/\/teliga.corsan.com.br\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-17.23.17.jpeg\" \/><\/a><\/div><div class=\"g-dyn a-6 c-3\"><a class=\"gofollow\" data-track=\"Niw2LDYw\" href=\"#\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2023\/01\/banner-agua-kangen-e1701887476486.jpeg\" \/><\/a><\/div><div class=\"g-dyn a-58 c-4\"><a class=\"gofollow\" data-track=\"NTgsNiw2MA==\" href=\"https:\/\/transformar.tramandai.rs.gov.br\/\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2026\/03\/TV-Nativoos-300-x-250-px.png\" \/><\/a><\/div><div class=\"g-dyn a-7 c-5\"><a class=\"gofollow\" data-track=\"Nyw2LDYw\" href=\"https:\/\/inovaimoveis.rs\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2023\/06\/Banner-Inova-300x214-1.jpeg\" \/><\/a><\/div><div class=\"g-dyn a-39 c-6\"><a class=\"gofollow\" data-track=\"MzksNiw2MA==\" href=\"https:\/\/tvnativoos.com.br\/wfe\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-17-at-19.58.28.jpeg\" \/><\/a><\/div><\/div>\n\n\n<p>O zagueiro tamb\u00e9m analisou as dificuldades encontradas ao longo da partida, especialmente pela postura da Chapecoense, que conseguiu incomodar em alguns momentos. Ainda assim, ressaltou a concentra\u00e7\u00e3o da equipe para construir o resultado. \u201cFoi um jogo complicado. A Chapecoense \u00e9 bem treinada, sabe pressionar e nos dificultou bastante. Mas conseguimos marcar no primeiro tempo e ampliar logo no in\u00edcio do segundo. O time esteve atento e comprometido o tempo todo, porque sab\u00edamos que precis\u00e1vamos muito dessa vit\u00f3ria\u201d, completou.<\/p>\n\n\n<div class=\"g g-8\"><div class=\"g-dyn a-44 c-1\"><a href=\"https:\/\/tvnativoos.com.br\/wfe\/radio-online-costeira-nativa\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2024\/06\/radiocosteiranativa-1.jpeg\" \/><\/a><\/div><div class=\"g-dyn a-45 c-2\"><a href=\"https:\/\/tvnativoos.com.br\/wfe\/radio-online-costeira-nativa\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2024\/06\/radiocosteiranativa-2.jpeg\" \/><\/a><\/div><\/div>\n\n\n<p>Com o triunfo, o Inter embala a segunda vit\u00f3ria consecutiva no Brasileir\u00e3o e ganha confian\u00e7a para a sequ\u00eancia da competi\u00e7\u00e3o. Ap\u00f3s a pausa para a data Fifa, o time volta a campo no dia 1\u00ba de abril, novamente no Beira-Rio, diante do S\u00e3o Paulo.<\/p>\n\n\n\n<p>Se inscreva em nosso canal do youtube.com\/@tvnativoos, curta nossa p\u00e1gina no facebook, instagram e o nosso portal\u00a0<a href=\"http:\/\/www.tvnativoos.com.br\/\">http:\/\/www.tvnativoos.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zagueiro comemora fim da sequ\u00eancia sem vit\u00f3rias e exalta atua\u00e7\u00e3o coletiva no 2 a 0 sobre a Chapecoense A\u00a0vit\u00f3ria por 2 a 0 sobre a Chapecoense, neste domingo, no Beira-Rio, marcou n\u00e3o apenas a sa\u00edda do\u00a0Inter\u00a0da zona de rebaixamento, mas tamb\u00e9m um momento de al\u00edvio para o grupo colorado. Um dos l\u00edderes da equipe, o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32027,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,2718],"tags":[223,65],"class_list":["post-32026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-primavera-2025","tag-esporte","tag-tvnativoos"],"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts\/32026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/comments?post=32026"}],"version-history":[{"count":2,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts\/32026\/revisions"}],"predecessor-version":[{"id":32029,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts\/32026\/revisions\/32029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/media\/32027"}],"wp:attachment":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/media?parent=32026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/categories?post=32026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/tags?post=32026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}