{"id":25401,"date":"2025-02-14T20:12:01","date_gmt":"2025-02-14T20:12:01","guid":{"rendered":"https:\/\/tvnativoos.com.br\/wfe\/?p=25401"},"modified":"2025-02-14T20:14:18","modified_gmt":"2025-02-14T20:14:18","slug":"balneario-pinhal-informativo","status":"publish","type":"post","link":"https:\/\/tvnativoos.com.br\/wfe\/balneario-pinhal-informativo\/","title":{"rendered":"Balne\u00e1rio Pinhal &#8211; Informativo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">CENTRO DE CONTROLE DE ZOONOSES<br>Com o compromisso de transformar Balne\u00e1rio Pinhal em uma cidade<br>ainda mais pr\u00f3spera e acolhedora, a nova gest\u00e3o, liderada pelo<br>prefeito Cezar Furini e o vice Jorge Fonseca, iniciou seus trabalhos no<br>dia 2 de janeiro de 2024.<br>Estamos cientes das necessidades da nossa cidade e, com um<br>trabalho conjunto que valoriza e resgata os nossos valores, vamos<br>buscar cada melhoria que Balne\u00e1rio Pinhal merece.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Departamento de Zoonoses: 30 Dias de Trabalho e alguns Desafios<br>Superados<br>Ao assumir a gest\u00e3o do Departamento de Zoonoses, a equipe<br>encontrou um cen\u00e1rio desafiador: maquin\u00e1rios defasados, estoque<br>reduzido de inseticidas e uma grande demanda por servi\u00e7os,<br>intensificada pelo per\u00edodo seco do ver\u00e3o, que favorece a prolifera\u00e7\u00e3o<br>de pragas urbanas. O setor, respons\u00e1vel pelo controle dessas pragas<br>e pela preven\u00e7\u00e3o de doen\u00e7as transmitidas por animais, rapidamente<br>estruturou um plano de a\u00e7\u00e3o para atender \u00e0s necessidades da<br>comunidade.<\/p>\n\n\n<div class=\"g g-6\"><div class=\"g-dyn a-7 c-1\"><a class=\"gofollow\" data-track=\"Nyw2LDYw\" href=\"https:\/\/inovaimoveis.rs\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2023\/06\/Banner-Inova-300x214-1.jpeg\" \/><\/a><\/div><div class=\"g-dyn a-58 c-2\"><a class=\"gofollow\" data-track=\"NTgsNiw2MA==\" href=\"https:\/\/transformar.tramandai.rs.gov.br\/\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2026\/07\/TRA-001526_Banner-300x250px_alt01.jpg\" \/><\/a><\/div><div class=\"g-dyn a-4 c-3\"><a class=\"gofollow\" data-track=\"NCw2LDYw\" href=\"https:\/\/arquitetalaurabaltar.com.br\/wfe\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2025\/01\/01-1.png\" \/><\/a><\/div><div class=\"g-dyn a-62 c-4\"><a class=\"gofollow\" data-track=\"NjIsNiw2MA==\" href=\": http:\/\/teliga.corsan.com.br\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-17.23.17.jpeg\" \/><\/a><\/div><div class=\"g-dyn a-39 c-5\"><a class=\"gofollow\" data-track=\"MzksNiw2MA==\" href=\"https:\/\/tvnativoos.com.br\/wfe\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-17-at-19.58.28.jpeg\" \/><\/a><\/div><div class=\"g-dyn a-6 c-6\"><a class=\"gofollow\" data-track=\"Niw2LDYw\" href=\"#\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2023\/01\/banner-agua-kangen-e1701887476486.jpeg\" \/><\/a><\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\"><br>Esporotricose: Um Alerta para a Popula\u00e7\u00e3o!<br>A esporotricose, doen\u00e7a que afeta especialmente a popula\u00e7\u00e3o felina<br>e pode ser transmitida para os humanos, foi identificada como uma<br>pequena epidemia na cidade. O tratamento \u00e9 espec\u00edfico e exige<br>conscientiza\u00e7\u00e3o da comunidade para evitar a dissemina\u00e7\u00e3o da<br>doen\u00e7a. O CCZ refor\u00e7a a import\u00e2ncia de procurar atendimento<br>imediato caso haja suspeita de contamina\u00e7\u00e3o, colaborando para<br>reduzir a circula\u00e7\u00e3o da enfermidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Equinos nas Vias P\u00fablicas: Risco e Conscientiza\u00e7\u00e3o!<br>A presen\u00e7a de cavalos soltos nas vias p\u00fablicas era uma situa\u00e7\u00e3o<br>alarmante, representando risco de acidentes, inclusive com v\u00edtimas<br>fatais. A estrat\u00e9gia adotada neste primeiro m\u00eas foi focada na<br>conscientiza\u00e7\u00e3o dos propriet\u00e1rios sobre a import\u00e2ncia da amarra\u00e7\u00e3o<br>correta, evitando o ato em propriedades privadas e locais<br>inadequados.<br>William, coordenador de Vigil\u00e2ncia, destaca um problema recorrente:<br>\u201cMuitos mun\u00edcipes acabam soltando os animais amarrados, seja por<br>acharem que est\u00e3o em situa\u00e7\u00e3o de maus-tratos ou para evitar danos<br>\u00e0s suas propriedades, mas essa pr\u00e1tica pode gerar um risco ainda<br>maior de acidentes.\u201d<br>Para situa\u00e7\u00f5es envolvendo cavalos soltos ou amarrados em locais<br>irregulares, o CCZ disponibiliza o contato (51) 99259-0809. A equipe se<br>desloca at\u00e9 o local para realizar o encaminhamento correto dos<br>animais. A a\u00e7\u00e3o inclui recolhimento, notifica\u00e7\u00e3o e, quando necess\u00e1rio,<br>aplica\u00e7\u00e3o de multas.<\/p>\n\n\n<div class=\"g g-7\"><div class=\"g-dyn a-7 c-1\"><a class=\"gofollow\" data-track=\"Nyw3LDYw\" href=\"https:\/\/inovaimoveis.rs\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2023\/06\/Banner-Inova-300x214-1.jpeg\" \/><\/a><\/div><div class=\"g-dyn a-6 c-2\"><a class=\"gofollow\" data-track=\"Niw3LDYw\" href=\"#\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2023\/01\/banner-agua-kangen-e1701887476486.jpeg\" \/><\/a><\/div><div class=\"g-dyn a-8 c-3\"><a class=\"gofollow\" data-track=\"OCw3LDYw\" href=\"https:\/\/www.facebook.com\/sonia.conti.7545\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2023\/06\/BANNERS-350X250-SONIA-CONTI-1-300x214-1.jpg\" \/><\/a><\/div><div class=\"g-dyn a-4 c-4\"><a class=\"gofollow\" data-track=\"NCw3LDYw\" href=\"https:\/\/arquitetalaurabaltar.com.br\/wfe\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2025\/01\/01-1.png\" \/><\/a><\/div><div class=\"g-dyn a-58 c-5\"><a class=\"gofollow\" data-track=\"NTgsNyw2MA==\" href=\"https:\/\/transformar.tramandai.rs.gov.br\/\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2026\/07\/TRA-001526_Banner-300x250px_alt01.jpg\" \/><\/a><\/div><div class=\"g-dyn a-62 c-6\"><a class=\"gofollow\" data-track=\"NjIsNyw2MA==\" href=\": http:\/\/teliga.corsan.com.br\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-19-at-17.23.17.jpeg\" \/><\/a><\/div><div class=\"g-dyn a-39 c-7\"><a class=\"gofollow\" data-track=\"MzksNyw2MA==\" href=\"https:\/\/tvnativoos.com.br\/wfe\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-17-at-19.58.28.jpeg\" \/><\/a><\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\"><br>Infraestrutura Prec\u00e1ria e Reformas Necess\u00e1rias<br>O Centro de Zoonoses encontra-se atualmente interditado para<br>novos resgates de c\u00e3es de rua, devido \u00e0s condi\u00e7\u00f5es prec\u00e1rias da<br>estrutura. A administra\u00e7\u00e3o municipal j\u00e1 iniciou os tr\u00e2mites para a<br>reforma do espa\u00e7o, garantindo um ambiente adequado e seguro<br>para o acolhimento e tratamento dos animais.<br>Os primeiros 30 dias de trabalho do Departamento de Zoonoses<br>demonstram um esfor\u00e7o cont\u00ednuo para melhorar o atendimento e a<br>qualidade de vida dos animais e da popula\u00e7\u00e3o. A meta da gest\u00e3o \u00e9<br>seguir avan\u00e7ando na estrutura\u00e7\u00e3o do setor, promovendo mais<br>efici\u00eancia, controle e bem-estar para todos.<br>Castra\u00e7\u00e3o e Controle Populacional<br>Um dos maiores desafios enfrentados pelo Centro de Controle de<br>Zoonoses (CCZ) \u00e9 a superpopula\u00e7\u00e3o de animais de rua, incluindo<br>c\u00e3es, gatos e equinos. No caso dos c\u00e3es, o munic\u00edpio conseguiu<br>dobrar, em apenas 30 dias, o n\u00famero de castra\u00e7\u00f5es em compara\u00e7\u00e3o<br>aos \u00faltimos meses de 2024. O objetivo agora \u00e9 reduzir a longa fila de<br>espera pelo procedimento, ampliando o atendimento tamb\u00e9m para<br>os felinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Compromisso com a Causa Animal<br>A causa animal \u00e9 uma demanda urgente no munic\u00edpio, exigindo um<br>olhar atento e uma estrutura adequada. Por isso, a administra\u00e7\u00e3o<br>municipal deseja implementar melhorias na infraestrutura do<br>departamento, com a cria\u00e7\u00e3o de um suporte cl\u00ednico mais eficiente<br>para o atendimento de animais em situa\u00e7\u00e3o de vulnerabilidade.<br>O Poder P\u00fablico tamb\u00e9m reconhece o trabalho essencial realizado<br>pelos grupos de protetores da causa animal. Muitos dedicam tempo,<br>cuidado e recursos pr\u00f3prios para garantir o bem-estar dos animais. O<br>munic\u00edpio busca estreitar essa parceria, fortalecendo a\u00e7\u00f5es conjuntas<br>que garantam melhores condi\u00e7\u00f5es para a popula\u00e7\u00e3o animal em<br>situa\u00e7\u00e3o de vulnerabilidade.<\/p>\n\n\n<div class=\"g g-8\"><div class=\"g-dyn a-44 c-1\"><a href=\"https:\/\/tvnativoos.com.br\/wfe\/radio-online-costeira-nativa\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2024\/06\/radiocosteiranativa-1.jpeg\" \/><\/a><\/div><div class=\"g-dyn a-45 c-2\"><a href=\"https:\/\/tvnativoos.com.br\/wfe\/radio-online-costeira-nativa\/\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/tvnativoos.com.br\/wfe\/wp-content\/uploads\/2024\/06\/radiocosteiranativa-2.jpeg\" \/><\/a><\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\">Curta, compartilhe e inscreva em nosso canal do\u00a0<a href=\"https:\/\/youtube.com\/@tvnativoos\">youtube.com\/@tvnativoos<\/a>, curta nossa p\u00e1gina no facebook, instagram e veja nossa programa\u00e7\u00e3o ao vivo portal\u00a0<a href=\"https:\/\/tvnativoos.com.br\/wfe\/clima-sexta-feira-sera-de-sol-no-rs\/\">www.tvnativoos.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CENTRO DE CONTROLE DE ZOONOSESCom o compromisso de transformar Balne\u00e1rio Pinhal em uma cidadeainda mais pr\u00f3spera e acolhedora, a nova [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":25404,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[65],"class_list":["post-25401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-tvnativoos"],"cc_featured_image_caption":{"caption_text":"Informa\u00e7\u00f5es de Balne\u00e1rio Pinhal - Comunica\u00e7\u00e3o","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts\/25401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/comments?post=25401"}],"version-history":[{"count":1,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts\/25401\/revisions"}],"predecessor-version":[{"id":25403,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/posts\/25401\/revisions\/25403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/media\/25404"}],"wp:attachment":[{"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/media?parent=25401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/categories?post=25401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvnativoos.com.br\/wfe\/wp-json\/wp\/v2\/tags?post=25401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}